{"id":334341,"date":"2022-09-21T00:40:09","date_gmt":"2022-09-21T00:40:09","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=334341"},"modified":"2024-11-24T17:50:31","modified_gmt":"2024-11-24T17:50:31","slug":"hams-al-ihsas-100ml-khalis-eau-de-parfum-damen","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/sv\/produkt\/hams-al-ihsas-100ml-khalis-eau-de-parfum-damen\/","title":{"rendered":"Hams Al Ihsas 100ml Khalis Eau de Parfum &#8211; Damen"},"content":{"rendered":"<ul>\n<li><strong>Marke<\/strong>: Khalis<\/li>\n<li><strong>Geschlecht<\/strong>: Damen<\/li>\n<li><strong style=\"color: #555555;\">Flakon<\/strong><span style=\"color: #555555;\">: Glas-Flakon.<\/span><\/li>\n<li><strong style=\"color: #555555;\">Duftkategorie<\/strong><span style=\"color: #555555;\">: orientalisch-holzig.<\/span><\/li>\n<li><strong style=\"color: #555555;\">Kopfnote<\/strong><span style=\"color: #555555;\">: Mandarine, Orange, Rose, Fruchtaroma, Tabak, Bergamotte, Dawanna.<\/span><\/li>\n<li><strong style=\"color: #555555;\">Herznote<\/strong><span style=\"color: #555555;\">: Gardenie, Honig, Jasmin, Orangenbl\u00fcte, Pfirsich, blumiges Bouquet (Jasmin, Patchouli, Gardenie, Maigl\u00f6ckchen und Jasmin), Tonkabohne.<\/span><\/li>\n<li><strong style=\"color: #555555;\">Basisnoten<\/strong><span style=\"color: #555555;\">: Karamell, Patchouli, Lakritze, Moschus, Mooseiche, Sandelholz, Vetiver, Patchouli<\/span><\/li>\n<li><strong style=\"color: #555555;\">Menge<\/strong><span style=\"color: #555555;\">: 100 EDP<\/span><\/li>\n<li><strong style=\"color: #555555;\">Herkunftsort<\/strong><span style=\"color: #555555;\">: in den Vereinigten Arabischen Emiraten<\/span><\/li>\n<\/ul>\n<p><small>Inhaltsstoff: Alkohol Denat, Parfum (Duft), Wasser (Aqua), Linalool, Limonene, Geraniol, Citronellol, Benzyl Alcohol, Amyl Cinnamal. Bitte beachten Sie, dass die Zutatenlisten f\u00fcr Produkte regelm\u00e4\u00dfig aktualisiert werden. Konsultieren Sie die Zutatenliste auf der Produktverpackung f\u00fcr die aktuellste Liste der Inhaltsstoffe.\u00a0<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marke: Khalis Geschlecht: Damen Flakon: Glas-Flakon. Duftkategorie: orientalisch-holzig. Kopfnote: Mandarine, Orange, Rose, Fruchtaroma, Tabak, Bergamotte, Dawanna. Herznote: Gardenie, Honig, Jasmin, Orangenbl\u00fcte, Pfirsich, blumiges Bouquet (Jasmin, Patchouli, Gardenie, Maigl\u00f6ckchen und Jasmin), Tonkabohne. Basisnoten: Karamell, Patchouli, Lakritze, Moschus, Mooseiche, Sandelholz, Vetiver, Patchouli Menge: 100 EDP Herkunftsort: in den Vereinigten Arabischen Emiraten Inhaltsstoff: Alkohol Denat, Parfum (Duft), Wasser [&#8230;]\n","protected":false},"featured_media":334342,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[87,1080,907,1088,98,1082],"product_tag":[],"class_list":["post-334341","product","type-product","status-publish","has-post-thumbnail","product_cat-sale","product_cat-damenduefte","product_cat-eau-de-parfum","product_cat-khalis","product_cat-parfuem","product_cat-parfum-marken","product_shipping_class-s-paket-495","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product\/334341","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/media\/334342"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/media?parent=334341"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_brand?post=334341"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_cat?post=334341"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_tag?post=334341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}