{"id":334027,"date":"2022-09-02T18:30:56","date_gmt":"2022-09-02T18:30:56","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=334027"},"modified":"2024-11-24T17:58:27","modified_gmt":"2024-11-24T17:58:27","slug":"supremacy-weihrauch-100ml-afnan-eau-de-parfum","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/sv\/produkt\/supremacy-weihrauch-100ml-afnan-eau-de-parfum\/","title":{"rendered":"Supremacy Incense 100ml Afnan Eau de Parfum &#8211; Herren"},"content":{"rendered":"<h1><strong>Supremacy Incense Herren Parfum von Afnan<\/strong><\/h1>\n<ul>\n<li><strong>Marke: <\/strong>Afnan<\/li>\n<li><strong>Volume: <\/strong>100ml<\/li>\n<li><strong>Geschlecht: <\/strong>Herren<\/li>\n<li><strong>Kopfnoten: <\/strong>Bergamotte, Oregano und Pfeffer<\/li>\n<li><strong>Herznoten: <\/strong>Bernstein, Labdanum und Opoponax<\/li>\n<li><strong>Basisnoten:<\/strong> Leder, Sandelholz, Patchouli und Oud<\/li>\n<li><strong>Konsistenz: <\/strong>Fl\u00fcssig<\/li>\n<li><strong>Herstellungsland: <\/strong>Vereinigte Arabische Emirate<\/li>\n<\/ul>\n<p>Willst du cool aber l\u00e4ssig sein? Ein perfektes Alltags-Parf\u00fcm f\u00fcr den Sommer &#8211; Supremacy Incense #CraftedByAfnan Hast du deines schon?<\/p>\n<p data-line-height=\"s\"><strong>Empfohlene Anwendung:<\/strong><\/p>\n<p data-line-height=\"s\">Den Duft auf die Haut auftragen und sanft auf der Innenseite des Handgelenks, Hals und Dekollet\u00e9 verteilen.<\/p>\n<p data-line-height=\"s\">Auf die gesunde Haut auftragen. Entflammbar, Kontakt mit Augen vermeiden. Nicht in die offene Flamme spr\u00fchen.<\/p>\n<p><small>Inhaltsstoff: Alkohol Denat, Parfum (Duft), Wasser (Aqua), Linalool, Limonene, Geraniol, Citronellol, Benzyl Alcohol, Amyl Cinnamal. Bitte beachten Sie, dass die Zutatenlisten f\u00fcr Produkte regelm\u00e4\u00dfig aktualisiert werden. Konsultieren Sie die Zutatenliste auf der Produktverpackung f\u00fcr die aktuellste Liste der Inhaltsstoffe.\u00a0<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Supremacy Incense Herren Parfum von Afnan Marke: Afnan Volume: 100ml Geschlecht: Herren Kopfnoten: Bergamotte, Oregano und Pfeffer Herznoten: Bernstein, Labdanum und Opoponax Basisnoten: Leder, Sandelholz, Patchouli und Oud Konsistenz: Fl\u00fcssig Herstellungsland: Vereinigte Arabische Emirate Willst du cool aber l\u00e4ssig sein? Ein perfektes Alltags-Parf\u00fcm f\u00fcr den Sommer &#8211; Supremacy Incense #CraftedByAfnan Hast du deines schon? Empfohlene [&#8230;]\n","protected":false},"featured_media":336338,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[1096,907,1079,98,1082],"product_tag":[],"class_list":["post-334027","product","type-product","status-publish","has-post-thumbnail","product_cat-afnan","product_cat-eau-de-parfum","product_cat-herrenduefte","product_cat-parfuem","product_cat-parfum-marken","product_shipping_class-s-paket-495","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product\/334027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/media\/336338"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/media?parent=334027"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_brand?post=334027"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_cat?post=334027"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_tag?post=334027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}