{"id":332121,"date":"2022-03-07T04:52:53","date_gmt":"2022-03-07T04:52:53","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=332121"},"modified":"2024-11-24T18:08:12","modified_gmt":"2024-11-24T18:08:12","slug":"gebetsteppich-mit-rueckenlehne","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/sv\/produkt\/gebetsteppich-mit-rueckenlehne\/","title":{"rendered":"Gebetsteppich mit R\u00fcckenlehne &#8211; Lila"},"content":{"rendered":"<div>\n<h1><strong>Gebetsteppich Sitzteppich mit Lehne Bodensitz <\/strong><\/h1>\n<p>&nbsp;<\/p>\n<ul>\n<li><span style=\"font-family: Trebuchet MS;\">Neue gem\u00fctliche Teppiche zum Anlehnen und Entspannen.\u00a0<\/span><\/li>\n<li><span style=\"font-family: Trebuchet MS;\">Ob als Gebetsteppich oder einfach als eine Sitzgelegenheit, der Teppich kann \u00fcberall eingesetzt werden.\u00a0<\/span><\/li>\n<li><span style=\"font-family: Trebuchet MS;\">Eine Transporttasche f\u00fcr den komfortablen Transport ist auch dabei. <\/span><\/li>\n<li>Gr\u00f6\u00dfe aufgeklappt: 110cm x 55cm<\/li>\n<li>Gewicht ca. 1,6kg<\/li>\n<li>Material 100% Polyester<\/li>\n<li>mit Motiv<\/li>\n<li><span class=\"a-list-item\">Inklusive schwarzer Tragetasche<\/span><\/li>\n<\/ul>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Gebetsteppich Sitzteppich mit Lehne Bodensitz &nbsp; Neue gem\u00fctliche Teppiche zum Anlehnen und Entspannen.\u00a0 Ob als Gebetsteppich oder einfach als eine Sitzgelegenheit, der Teppich kann \u00fcberall eingesetzt werden.\u00a0 Eine Transporttasche f\u00fcr den komfortablen Transport ist auch dabei. Gr\u00f6\u00dfe aufgeklappt: 110cm x 55cm Gewicht ca. 1,6kg Material 100% Polyester mit Motiv Inklusive schwarzer Tragetasche<\/p>\n","protected":false},"featured_media":332124,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[866,86],"product_tag":[],"class_list":["post-332121","product","type-product","status-publish","has-post-thumbnail","product_cat-erwachsene-gebetsteppich","product_cat-gebetsteppich","product_shipping_class-s-paket-495","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product\/332121","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/media\/332124"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/media?parent=332121"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_brand?post=332121"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_cat?post=332121"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/sv\/wp-json\/wp\/v2\/product_tag?post=332121"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}