{"id":331549,"date":"2022-01-21T00:37:45","date_gmt":"2022-01-21T00:37:45","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=331549"},"modified":"2026-02-18T15:45:32","modified_gmt":"2026-02-18T15:45:32","slug":"mekka-gebetsteppich-orange-schwarz","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/pl\/produkt\/mekka-gebetsteppich-orange-schwarz\/","title":{"rendered":"Gebetsteppich Kaaba Kiswah 610g"},"content":{"rendered":"<h1><strong>Kaaba Gebetsteppich<\/strong><\/h1>\n<ul>\n<li>Weicher, glatter Gebetsteppich<\/li>\n<li>Abmessungen ca.: 110 x 70 cm.<\/li>\n<li>Die Matte wiegt ungef\u00e4hr 610g.<\/li>\n<li>Neu gestalteter Gebetsteppich mit sch\u00f6nen Mustern.<\/li>\n<li>Material: 100% Baumwolle<\/li>\n<li>Hergestellt in der T\u00fcrkei<\/li>\n<li>ideales Geschenk f\u00fcr eine Familie oder eine Masjid, in der viele Menschen beten.<\/li>\n<li>Verschenken Sie diesen Gebetsteppich an jemanden, der seine f\u00fcnf t\u00e4glichen Gebete verrichtet, und Ihre Belohnung wird anhalten.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Kaaba Gebetsteppich Weicher, glatter Gebetsteppich Abmessungen ca.: 110 x 70 cm. Die Matte wiegt ungef\u00e4hr 610g. Neu gestalteter Gebetsteppich mit sch\u00f6nen Mustern. Material: 100% Baumwolle Hergestellt in der T\u00fcrkei ideales Geschenk f\u00fcr eine Familie oder eine Masjid, in der viele Menschen beten. Verschenken Sie diesen Gebetsteppich an jemanden, der seine f\u00fcnf t\u00e4glichen Gebete verrichtet, und [&#8230;]\n","protected":false},"featured_media":333685,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[866,86],"product_tag":[],"class_list":["post-331549","product","type-product","status-publish","has-post-thumbnail","product_cat-erwachsene-gebetsteppich","product_cat-gebetsteppich","product_shipping_class-s-paket-495","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/product\/331549","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/media\/333685"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/media?parent=331549"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/product_brand?post=331549"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/product_cat?post=331549"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/pl\/wp-json\/wp\/v2\/product_tag?post=331549"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}