{"id":334436,"date":"2022-09-25T00:39:08","date_gmt":"2022-09-25T00:39:08","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=334436"},"modified":"2024-11-24T17:50:19","modified_gmt":"2024-11-24T17:50:19","slug":"ramz-lattafa-gold-100ml-lattafa-eau-de-parfum-unisex","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/nl\/produkt\/ramz-lattafa-gold-100ml-lattafa-eau-de-parfum-unisex\/","title":{"rendered":"Ramz Lattafa Gold 100ml Lattafa Eau de Parfum &#8211; Unisex"},"content":{"rendered":"<ul>\n<li><strong>Marke<\/strong>: Lattafa<\/li>\n<li><strong>Type:<\/strong> Eau de Parfum<\/li>\n<li><strong>Geschlecht<\/strong>: F\u00fcr Herren und Damen<\/li>\n<li><strong>Kopfnoten<\/strong>: Bergamotte, Apfel und Ananas<\/li>\n<li><strong>Herznoten<\/strong>: Birke, Patchouli und Jasmin<\/li>\n<li><strong>Basisnoten<\/strong>: Moschus, Eichenmoos, Leder und Bernstein<\/li>\n<li><strong>Menge<\/strong>: 100ml Parfum<\/li>\n<li><strong>Herkunftsort<\/strong>: in den Vereinigten Arabischen Emiraten<\/li>\n<li>Enth\u00e4lt denaturierten Alkohol (halal)<\/li>\n<\/ul>\n<p>Lattafa Ramz (Gold) ist inspiriert vom unwiderstehlichen Akt der Ann\u00e4herung. Der orientalische Duft f\u00fcr Sie und Ihn wurde entwickelt, um eine verborgene Kraft auszul\u00f6sen, die die Person, die ihn tr\u00e4gt, mit einer fesselnden Anziehungskraft umh\u00fcllt.<\/p>\n<p><small>Inhaltsstoff: Alkohol Denat, Parfum (Duft), Wasser (Aqua), Linalool, Limonene, Geraniol, Citronellol, Benzyl Alcohol, Amyl Cinnamal. Bitte beachten Sie, dass die Zutatenlisten f\u00fcr Produkte regelm\u00e4\u00dfig aktualisiert werden. Konsultieren Sie die Zutatenliste auf der Produktverpackung f\u00fcr die aktuellste Liste der Inhaltsstoffe.\u00a0<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marke: Lattafa Type: Eau de Parfum Geschlecht: F\u00fcr Herren und Damen Kopfnoten: Bergamotte, Apfel und Ananas Herznoten: Birke, Patchouli und Jasmin Basisnoten: Moschus, Eichenmoos, Leder und Bernstein Menge: 100ml Parfum Herkunftsort: in den Vereinigten Arabischen Emiraten Enth\u00e4lt denaturierten Alkohol (halal) Lattafa Ramz (Gold) ist inspiriert vom unwiderstehlichen Akt der Ann\u00e4herung. Der orientalische Duft f\u00fcr Sie [&#8230;]\n","protected":false},"featured_media":334437,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[907,1084,98,1082,1081],"product_tag":[],"class_list":["post-334436","product","type-product","status-publish","has-post-thumbnail","product_cat-eau-de-parfum","product_cat-lattafa","product_cat-parfuem","product_cat-parfum-marken","product_cat-unisex-duefte","product_shipping_class-s-paket-495","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product\/334436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/media\/334437"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/media?parent=334436"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product_brand?post=334436"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product_cat?post=334436"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product_tag?post=334436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}