{"id":328135,"date":"2021-07-04T04:03:29","date_gmt":"2021-07-04T04:03:29","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=328135"},"modified":"2026-06-16T22:46:45","modified_gmt":"2026-06-16T22:46:45","slug":"weihrauchstaebchen-taif-rose","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/nl\/produkt\/weihrauchstaebchen-taif-rose\/","title":{"rendered":"Weihrauchst\u00e4bchen Taif Rose"},"content":{"rendered":"<h1><strong>Weihrauchst\u00e4bchen Taif Rose<\/strong><\/h1>\n<ul>\n<li>Duft: Taeif Rosen<\/li>\n<li>1x Packung 15 sticks.<\/li>\n<li>L\u00e4nge ca 22cm<\/li>\n<li>Brendauer: ca 45 Minuten<\/li>\n<li>Marke: Karamat<\/li>\n<li>Produkttyp: Aromatische R\u00e4ucherst\u00e4bchen<\/li>\n<li>Material: Bambus<\/li>\n<li>Farbe: Schwarz R\u00e4ucherst\u00e4bchen<\/li>\n<li>Hergestellt in Indien<\/li>\n<li>Perfekt f\u00fcr den t\u00e4glichen Gebrauch<\/li>\n<li>Auch ideal als Geschenk f\u00fcr alle Anl\u00e4sse: Islamische Feiertage, Hochzeitsveranstaltungen. Spa, Meditation, Entspannung<\/li>\n<li>Achtung: Lassen Sie die angez\u00fcndeten R\u00e4ucherst\u00e4bchen niemals unbeaufsichtigt und verwenden Sie immer eine nicht brennbare Unterlage!<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Weihrauchst\u00e4bchen Taif Rose Duft: Taeif Rosen 1x Packung 15 sticks. L\u00e4nge ca 22cm Brendauer: ca 45 Minuten Marke: Karamat Produkttyp: Aromatische R\u00e4ucherst\u00e4bchen Material: Bambus Farbe: Schwarz R\u00e4ucherst\u00e4bchen Hergestellt in Indien Perfekt f\u00fcr den t\u00e4glichen Gebrauch Auch ideal als Geschenk f\u00fcr alle Anl\u00e4sse: Islamische Feiertage, Hochzeitsveranstaltungen. Spa, Meditation, Entspannung Achtung: Lassen Sie die angez\u00fcndeten R\u00e4ucherst\u00e4bchen niemals [&#8230;]\n","protected":false},"featured_media":328128,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[908,106],"product_tag":[803],"class_list":["post-328135","product","type-product","status-publish","has-post-thumbnail","product_cat-raeucherstaebchen","product_cat-weihrauch","product_tag-taif","product_shipping_class-s-paket-495","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product\/328135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/media\/328128"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/media?parent=328135"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product_brand?post=328135"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product_cat?post=328135"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/nl\/wp-json\/wp\/v2\/product_tag?post=328135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}