{"id":344008,"date":"2024-07-29T00:43:47","date_gmt":"2024-07-29T00:43:47","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=344008"},"modified":"2025-01-06T08:10:13","modified_gmt":"2025-01-06T08:10:13","slug":"oud-maknoon-45ml-swiss-arabian-eau-de-parfum-unisex","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/fr\/produkt\/oud-maknoon-45ml-swiss-arabian-eau-de-parfum-unisex\/","title":{"rendered":"Oud Maknoon 45ml Swiss Arabian Eau de Parfum &#8211; Unisex"},"content":{"rendered":"<ul>\n<li><strong>Marke<\/strong>: Swiss Arabian<\/li>\n<li><strong>Geeignet f\u00fcr<\/strong>: Unisex<\/li>\n<li><strong>Menge<\/strong>:45ml<\/li>\n<li><strong>Type:<\/strong> Eau de Parfum<\/li>\n<li><strong>Duftfamilie<\/strong>: Blumig, holzig, bernsteinfarben<\/li>\n<li><strong>Kopfnote<\/strong>: Kamille, Aprikose, Amalfi-Zitrone<\/li>\n<li><strong>Herznote<\/strong>: Weihrauch (Luban), Orris<\/li>\n<li><strong>Basisnote<\/strong>: Moschus, Amber, Leder, Vanille, Virginiazeder<\/li>\n<li><strong>Herkunftsort<\/strong>: in den Vereinigten Arabischen Emiraten<\/li>\n<\/ul>\n<h3><strong>OUD MAKNOON 45ML<\/strong><\/h3>\n<p class=\"\">Es ist ein intensiv blumiger, ambrafarbener Oud-Duft mit einer w\u00fcrzigen Note, der ihn und Sie unvergesslich macht. Es bietet ein neues Ma\u00df an Luxus f\u00fcr diejenigen, die das Au\u00dfergew\u00f6hnliche erkennen und sich in seinen Schichten kostbaren goldenen Ouds sonnen m\u00f6chten. Mit einem unverwechselbaren Bouquet aus Artemisia, Kamille, Aprikose und Zitrone gibt dieser kr\u00e4uterige Zitrusakkord den Ton f\u00fcr eine epische Duftreise an. Hauchhauchd\u00fcnne Weihrauchschwaden umgeben die Herznote des Duftes, verleihen der seltenen Iris Tiefe und bieten die perfekte Plattform f\u00fcr die Basisnoten. Warme Vanille und Moschus umarmen Sie, w\u00e4hrend sich erdiges Leder und seidiger Amber zu einem klangvollen goldenen Finish vereinen. Erhabenes Oud spielt die Hauptrolle und sorgt f\u00fcr ein langanhaltendes Finale der Unterscheidung. Oud Maknoon ist ein Unisex-Duft, geeignet f\u00fcr k\u00fchlere N\u00e4chte. Entdecken Sie verborgene Wunder.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marke: Swiss Arabian Geeignet f\u00fcr: Unisex Menge:45ml Type: Eau de Parfum Duftfamilie: Blumig, holzig, bernsteinfarben Kopfnote: Kamille, Aprikose, Amalfi-Zitrone Herznote: Weihrauch (Luban), Orris Basisnote: Moschus, Amber, Leder, Vanille, Virginiazeder Herkunftsort: in den Vereinigten Arabischen Emiraten OUD MAKNOON 45ML Es ist ein intensiv blumiger, ambrafarbener Oud-Duft mit einer w\u00fcrzigen Note, der ihn und Sie unvergesslich macht. [&#8230;]\n","protected":false},"featured_media":344018,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[907,1079,98,1090],"product_tag":[],"class_list":["post-344008","product","type-product","status-publish","has-post-thumbnail","product_cat-eau-de-parfum","product_cat-herrenduefte","product_cat-parfuem","product_cat-swiss-arabian","product_shipping_class-s-paket-495","first","outofstock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/product\/344008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/media\/344018"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/media?parent=344008"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/product_brand?post=344008"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/product_cat?post=344008"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/fr\/wp-json\/wp\/v2\/product_tag?post=344008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}