{"id":338615,"date":"2023-10-24T11:24:49","date_gmt":"2023-10-24T11:24:49","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=338615"},"modified":"2024-11-24T17:40:38","modified_gmt":"2024-11-24T17:40:38","slug":"woody-duftkerze-von-karamat-collection","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/es\/produkt\/woody-duftkerze-von-karamat-collection\/","title":{"rendered":"Woody Duftkerze von Karamat Collection"},"content":{"rendered":"<ul>\n<li>Marke: Karamat Collection<\/li>\n<li>F\u00fcllung: ca. 170g<\/li>\n<li><span class=\"pdp-Specifics_ItemName\">Brenndauer:<\/span> ca. <span class=\"pdp-Specifics_ItemDescription\">40 <span class=\"pdp-Specifics_ItemName\">Std<\/span><\/span><\/li>\n<li>Duftrichtung: Eine Mischung aus Zedernholz, Sandelholz, Moschus und Rosen.<\/li>\n<li>Anwendungsbereich: Wohnzimmer<\/li>\n<li><span class=\"classification__item classification__item--bold\">Material: <\/span><span class=\"classification__item\">Glas<\/span><\/li>\n<li>Form: rund<\/li>\n<li><span class=\"classification__item classification__item--bold\">Geschenk f\u00fcr: <\/span><span class=\"classification__item\">Eid (opferfest , Fest des Fastenbrechens), Ramadan, Geburtstag, Weihnachten &#8230;\u00a0<\/span><\/li>\n<li>Gewicht: 220 gr<\/li>\n<li>Herstellungsland: Belgien<\/li>\n<li style=\"list-style-type: none;\"><\/li>\n<\/ul>\n<p>F\u00fcr einen gem\u00fctlichen und warmen Raum ist diese Woody-Kerze einfach perfekt.<\/p>\n<p>Dieser treffend benannte Duft verbreitet sich mit Zedern- und Sandelholz, umarmt von Rosen und Moschus.<\/p>\n<p><strong>VERWENDUNG<\/strong><\/p>\n<p>Damit die Kerze gleichm\u00e4\u00dfig brennt, sollte sie beim ersten Anz\u00fcnden so lange brennen, bis sich die oberste Wachsschicht vollst\u00e4ndig aufgel\u00f6st hat, was in der Regel etwa 3-4 Stunden dauert.<\/p>\n<p><strong>Warunung:<\/strong><\/p>\n<p>Bitte lassen Sie brennende Kerzen niemals unbeaufsichtigt. Die Verwendung von Kerzen geschieht auf eigenes Risiko. Stellen Sie sicher, dass Kerzen immer au\u00dferhalb der Reichweite von Kindern und Haustieren aufgestellt sind.<\/p>\n<p>Die Liste der Inhaltsstoffe der Karamat-D\u00fcfte wird regelm\u00e4\u00dfig aktualisiert. Bevor Sie dieses Karamat-Produkt verwenden, lesen Sie bitte die Liste der Inhaltsstoffe auf der Verpackung, um sicherzustellen, dass sie f\u00fcr Ihren pers\u00f6nlichen Gebrauch geeignet sind.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marke: Karamat Collection F\u00fcllung: ca. 170g Brenndauer: ca. 40 Std Duftrichtung: Eine Mischung aus Zedernholz, Sandelholz, Moschus und Rosen. Anwendungsbereich: Wohnzimmer Material: Glas Form: rund Geschenk f\u00fcr: Eid (opferfest , Fest des Fastenbrechens), Ramadan, Geburtstag, Weihnachten &#8230;\u00a0 Gewicht: 220 gr Herstellungsland: Belgien F\u00fcr einen gem\u00fctlichen und warmen Raum ist diese Woody-Kerze einfach perfekt. Dieser treffend [&#8230;]\n","protected":false},"featured_media":338596,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[87,1120,1113],"product_tag":[],"class_list":["post-338615","product","type-product","status-publish","has-post-thumbnail","product_cat-sale","product_cat-duftkerzen","product_cat-karamat-collection","product_shipping_class-s-paket-495","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product\/338615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/media\/338596"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/media?parent=338615"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_brand?post=338615"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_cat?post=338615"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_tag?post=338615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}