{"id":338415,"date":"2023-10-17T23:16:38","date_gmt":"2023-10-17T23:16:38","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=338415"},"modified":"2025-11-23T19:54:32","modified_gmt":"2025-11-23T19:54:32","slug":"qisa-3-100ml-maryaj-eau-de-parfum-unisex","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/es\/produkt\/qisa-3-100ml-maryaj-eau-de-parfum-unisex\/","title":{"rendered":"Qisa-3 50ml Maryaj Eau de Parfum &#8211; Unisex"},"content":{"rendered":"<ul>\n<li>Marke: Maryaj by Ajmal Perfumes<\/li>\n<li>Inhalt: 50ml<\/li>\n<li>Empfehlung: f\u00fcr Herren und Damen<\/li>\n<li>Flakon mit Spr\u00fchd\u00fcse<\/li>\n<li>Herstellungsland: Vereinigten Arabischen Emirat<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Viele unvergessliche Anekdoten k\u00f6nnen mit dem wundersch\u00f6nen Duft von Qisa &#8211; 3 von Maryaj entdeckt und neu erz\u00e4hlt werden. Wenn Sie seine Kopfnoten \u00f6ffnen, werden blumige Nuancen einer frischen Rose und einer verf\u00fchrerischen Jasmin Sie sofort verzaubern. Und wenn Sie durch sein mittleres Kapitel reisen, ist sein holziges Herz von der Gelassenheit des Sandelholzes und der Heiterkeit des Patchouli durchdrungen. Schlie\u00dflich erreicht sein Bouquet einen gro\u00dfartigen H\u00f6hepunkt; das Triumvirat aus Amber, Moschus und einem Oudh-Akkord bringt ein temperamentvolles Finale hervor, das ambriert, moschusartig und oudhig ist.<\/p>\n<p><small>Inhaltsstoff: Alkohol Denat, Parfum (Duft), Wasser (Aqua), Linalool, Limonene, Geraniol, Citronellol, Benzyl Alcohol, Amyl Cinnamal. Bitte beachten Sie, dass die Zutatenlisten f\u00fcr Produkte regelm\u00e4\u00dfig aktualisiert werden. Konsultieren Sie die Zutatenliste auf der Produktverpackung f\u00fcr die aktuellste Liste der Inhaltsstoffe.\u00a0<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marke: Maryaj by Ajmal Perfumes Inhalt: 50ml Empfehlung: f\u00fcr Herren und Damen Flakon mit Spr\u00fchd\u00fcse Herstellungsland: Vereinigten Arabischen Emirat &nbsp; Viele unvergessliche Anekdoten k\u00f6nnen mit dem wundersch\u00f6nen Duft von Qisa &#8211; 3 von Maryaj entdeckt und neu erz\u00e4hlt werden. Wenn Sie seine Kopfnoten \u00f6ffnen, werden blumige Nuancen einer frischen Rose und einer verf\u00fchrerischen Jasmin Sie [&#8230;]\n","protected":false},"featured_media":338417,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[87,907,1118,1207,1081],"product_tag":[],"class_list":["post-338415","product","type-product","status-publish","has-post-thumbnail","product_cat-sale","product_cat-eau-de-parfum","product_cat-maryaj","product_cat-sale-week","product_cat-unisex-duefte","product_shipping_class-s-paket-495","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product\/338415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/media\/338417"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/media?parent=338415"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_brand?post=338415"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_cat?post=338415"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_tag?post=338415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}