{"id":331217,"date":"2021-12-21T00:10:21","date_gmt":"2021-12-21T00:10:21","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=331217"},"modified":"2024-11-24T19:54:20","modified_gmt":"2024-11-24T19:54:20","slug":"khanjar-lufterfrischer-300ml-von-myperfumes","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/es\/produkt\/khanjar-lufterfrischer-300ml-von-myperfumes\/","title":{"rendered":"Khanjar Lufterfrischer 300ml von Myperfumes"},"content":{"rendered":"<h1><strong>Raumduft Khanjar\u00a0<\/strong><\/h1>\n<ul>\n<li>Marke: MyPERFUMES \u2013 ARABIYAT<\/li>\n<li>Inhalt: 300ml<\/li>\n<li class=\"forproduct mb-2\">Raumspray aus dem Orient<\/li>\n<li>Duftrichtung: Orientalisch<\/li>\n<li>Hergestellt In den Vereinigten Arabischen Emiraten (VAE)<\/li>\n<li class=\"forproduct mb-2\">ideal f\u00fcr: Ihre Wohnung, B\u00fcro, Moschee, Haus, Restaurant, Friseursalon, Badezimmern, Auto Innenraum..<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<hr \/>\n<div class=\"jl\" data-dmid=\"product-detail-item-accordion-content-text\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"b dt\" src=\"https:\/\/media.dm-static.com\/images\/v1538632925\/products\/pim\/FLAME\/FLAME.svg\" alt=\"ghsSymbol0\" width=\"57\" height=\"57\" data-dmid=\"symbol-image\" \/><span style=\"font-size: 80%;\"><img loading=\"lazy\" decoding=\"async\" class=\"\" src=\"https:\/\/m.media-amazon.com\/images\/I\/31mTHI4a8xL.png\" alt=\"Verursacht schwere Augenreizung.\" width=\"52\" height=\"51\" \/><\/span><\/p>\n<\/div>\n<p class=\"description\"><b>Sicherheitshinweise:<\/b><\/p>\n<p class=\"description\"><b>Aufbewahrung<\/b>: Vor Sonnenbestrahlung sch\u00fctzen Temperaturen von mehr als 50 \u00b0C vermeiden. Nur in gut gel\u00fcfteten R\u00e4umen verwenden. Personen, die auf Duftstoffe empfindlich reagieren, sollten dieses Produkt mit Vorsicht verwenden.<\/p>\n<p class=\"description\"><b>Gefahrenhinweis<\/b>: Extrem entz\u00fcndbares Aerosol\u00a0 Beh\u00e4lter steht unter Druck. Kann bei Erw\u00e4rmung bersten. Nach Gebrauch nicht gewaltsam \u00f6ffnen oder verbrennen. Nicht gegen Flamme oder auf gl\u00fchenden Gegenstand spr\u00fchen.<\/p>\n<p class=\"description\"><b>Sicherheitshinweis<\/b>: Darf nicht in die H\u00e4nde von Kindern gelangen. Von Z\u00fcndquellen fernhalten . Aerosol nicht einatmen. Ber\u00fchrung mit den Augen vermeiden. Bei Ber\u00fchrung mit den Augen sofort gr\u00fcndlich mit Wasser absp\u00fclen und Arzt aufsuchen. Bei Verschlucken umgehend \u00e4rztlichen Rat einholen und Verpackung oder Etikett vorzeigen. Nicht durchstechen oder verbrennen, auch nicht nach der Verwendung.<\/p>\n<p class=\"description\"><strong>Inhaltsstoff:<\/strong> Alcohol Denat, ISO Propylmyristate, Parfum (Fragrance), Anise Alcohol, Benzyl Alcohol, Benzyl Benzoate, Benzyl Salicylate, Cinnamyl, Alcohol, Citral, Citronellol, Geraniol, Limonene, Butan, Propane.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Raumduft Khanjar\u00a0 Marke: MyPERFUMES \u2013 ARABIYAT Inhalt: 300ml Raumspray aus dem Orient Duftrichtung: Orientalisch Hergestellt In den Vereinigten Arabischen Emiraten (VAE) ideal f\u00fcr: Ihre Wohnung, B\u00fcro, Moschee, Haus, Restaurant, Friseursalon, Badezimmern, Auto Innenraum.. &nbsp; Sicherheitshinweise: Aufbewahrung: Vor Sonnenbestrahlung sch\u00fctzen Temperaturen von mehr als 50 \u00b0C vermeiden. Nur in gut gel\u00fcfteten R\u00e4umen verwenden. Personen, die auf [&#8230;]\n","protected":false},"featured_media":331213,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[98,880],"product_tag":[],"class_list":["post-331217","product","type-product","status-publish","has-post-thumbnail","product_cat-parfuem","product_cat-raumspray","product_shipping_class-s-paket-495","first","outofstock","taxable","shipping-taxable","purchasable","product-type-variable"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product\/331217","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/media\/331213"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/media?parent=331217"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_brand?post=331217"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_cat?post=331217"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/es\/wp-json\/wp\/v2\/product_tag?post=331217"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}