{"id":331479,"date":"2022-01-12T01:07:08","date_gmt":"2022-01-12T01:07:08","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=331479"},"modified":"2024-11-24T20:46:13","modified_gmt":"2024-11-24T20:46:13","slug":"kinder-gebetsteppich-haddsch-motiv-hellblau","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/en\/produkt\/kinder-gebetsteppich-haddsch-motiv-hellblau\/","title":{"rendered":"Kinder Gebetsteppich &#8211; Haddsch Motiv &#8211; Hellblau"},"content":{"rendered":"<h1><strong><span style=\"font-size: 100%;\">Kindegebetsteppich &#8211; Haddsch Motiv- Hellblau<\/span><\/strong><\/h1>\n<ul>\n<li>Gr\u00f6\u00dfe: 50 x 90 cm<\/li>\n<li>Gebetsteppich in verschiedenen Farben erh\u00e4ltlich<\/li>\n<li>ideale f\u00fcr Kinder als auch f\u00fcr Erwachsene<\/li>\n<li>Anti-Rutsch-Beschichtung<\/li>\n<li>islamische Muster: Kaaba<\/li>\n<li>Teppich mit goldenen Fransen<\/li>\n<li>gl\u00e4nzend und f\u00fchlt sich herrlich weich an<\/li>\n<li>Sehr sch\u00f6ne Verarbeitung<\/li>\n<li>perfekt um Ihr Kind schon fr\u00fch an das Gebet zu gew\u00f6hnen.<\/li>\n<li>Material:\u00a0100% Polyester<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Kindegebetsteppich &#8211; Haddsch Motiv- Hellblau Gr\u00f6\u00dfe: 50 x 90 cm Gebetsteppich in verschiedenen Farben erh\u00e4ltlich ideale f\u00fcr Kinder als auch f\u00fcr Erwachsene Anti-Rutsch-Beschichtung islamische Muster: Kaaba Teppich mit goldenen Fransen gl\u00e4nzend und f\u00fchlt sich herrlich weich an Sehr sch\u00f6ne Verarbeitung perfekt um Ihr Kind schon fr\u00fch an das Gebet zu gew\u00f6hnen. Material:\u00a0100% Polyester<\/p>\n","protected":false},"featured_media":333610,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[86,865],"product_tag":[],"class_list":["post-331479","product","type-product","status-publish","has-post-thumbnail","product_cat-gebetsteppich","product_cat-kinder-gebetsteppich","product_shipping_class-s-paket-495","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product\/331479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/media\/333610"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/media?parent=331479"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product_brand?post=331479"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product_cat?post=331479"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product_tag?post=331479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}