{"id":328712,"date":"2021-07-18T18:38:19","date_gmt":"2021-07-18T18:38:19","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=328712"},"modified":"2024-11-24T20:25:06","modified_gmt":"2024-11-24T20:25:06","slug":"weisser-moschus-tahara-seife","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/en\/produkt\/weisser-moschus-tahara-seife\/","title":{"rendered":"Wei\u00dfer Moschus Tahara Seife"},"content":{"rendered":"<h1>Wei\u00dfer Moschus Tahara Seife<\/h1>\n<ul class=\"a-unordered-list a-vertical a-spacing-mini\">\n<li><span class=\"a-list-item\">Produkttyp: St\u00fcckseife<\/span><\/li>\n<li><span class=\"a-list-item\">Anwendungsbereich: K\u00f6rper<\/span><\/li>\n<li><span class=\"a-list-item\">Gewicht: 125g, Duft: Moschus Tahara &#8220;Musk Tahara&#8221;<\/span><\/li>\n<li><span class=\"a-list-item\">Aufbewahrungshinweise: nach Gebrauch abtropfen und abtrocknen lassen.<\/span><\/li>\n<li><span class=\"a-list-item\">Musc Tahara Seife ist reich an Teebaum\u00f6l, Es wird speziell f\u00fcr die Haut verwendet und Kopfhautprobleme, Es ist Bekannt f\u00fcr seine antibakterielle Formel, es ist effektiv ggen kopfhautprobleme wie Schuppen und Hautprobleme wie Ekzeme und Pilze.<\/span><\/li>\n<li>Warnhinweise: Kann, durch die lange Lagerung in Gew\u00f6lbekellern, Staub Partikel auf der Oberfl\u00e4che enthalten. Daher bitte vor der ersten Nutzung kurz abwaschen.<\/li>\n<li>Gebrauchsanweisung: Bitte vor der ersten Nutzung die oberste Schicht abwaschen, aufgrund der langen Lagerung in Gew\u00f6lbe Kellern.<\/li>\n<li>Inhaltstoffe: Natriumpalmat, Natriumpalmkernelat, EU Oliven\u00f6l, Frucht\u00f6l, Glycerin, Oryza Sativa Germ \u00d6l, Oryza Sativa Germ P\u00fclver, Benzyl Salicylate, Hexyl Cinnamal, Hydroxycitronellal.<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Wei\u00dfer Moschus Tahara Seife Produkttyp: St\u00fcckseife Anwendungsbereich: K\u00f6rper Gewicht: 125g, Duft: Moschus Tahara &#8220;Musk Tahara&#8221; Aufbewahrungshinweise: nach Gebrauch abtropfen und abtrocknen lassen. Musc Tahara Seife ist reich an Teebaum\u00f6l, Es wird speziell f\u00fcr die Haut verwendet und Kopfhautprobleme, Es ist Bekannt f\u00fcr seine antibakterielle Formel, es ist effektiv ggen kopfhautprobleme wie Schuppen und Hautprobleme wie [&#8230;]\n","protected":false},"featured_media":328690,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[970,872],"product_tag":[],"class_list":["post-328712","product","type-product","status-publish","has-post-thumbnail","product_cat-bazar","product_cat-seife","product_shipping_class-s-paket-495","first","instock","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product\/328712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/media\/328690"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/media?parent=328712"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product_brand?post=328712"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product_cat?post=328712"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/en\/wp-json\/wp\/v2\/product_tag?post=328712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}