{"id":344009,"date":"2024-07-29T00:40:28","date_gmt":"2024-07-29T00:40:28","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=344009"},"modified":"2025-12-26T17:59:12","modified_gmt":"2025-12-26T17:59:12","slug":"kashkha-50ml-swiss-arabian-eau-de-parfum-damen","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/cs\/produkt\/kashkha-50ml-swiss-arabian-eau-de-parfum-damen\/","title":{"rendered":"Kashkha 50ml Swiss Arabian Eau de Parfum &#8211; Damen"},"content":{"rendered":"<ul>\n<li><strong>Marke<\/strong>: Swiss Arabian<\/li>\n<li><strong>Geeignet f\u00fcr<\/strong>: Damen<\/li>\n<li><strong>Menge<\/strong>: 50ml<\/li>\n<li><strong>Type:<\/strong> Eau de Parfum<\/li>\n<li><strong>Duftfamilie<\/strong>: Orientalisch, Fruchtig, Amber, Holzig<\/li>\n<li><strong>Kopfnote<\/strong>: Bergamotte, Apfel, Zimt<\/li>\n<li><strong>Herznote<\/strong>: Safran, Kardamom, Oud<\/li>\n<li><strong>Basisnote<\/strong>: Zedernholz, Amber, Moschus<\/li>\n<li><strong>Herkunftsort<\/strong>: in den Vereinigten Arabischen Emiraten<\/li>\n<\/ul>\n<h3><strong>KASHKA EAU DE PARFUM 50ML<\/strong><\/h3>\n<p class=\"\">Kashkha ist ein fruchtiger, w\u00fcrziger Oud-Duft, inspiriert von modernen M\u00e4nnern und Frauen, die in allem, was sie tun, Stil verk\u00f6rpern. Wenn sie Kashkha in die Hand nehmen, wissen sie, dass ihr Duft genauso stilvoll ist wie sie selbst. Kashkha gibt seine Noten eine nach der anderen ab, wie duftende Duftblasen. Der Duft beginnt mit scharfen und klaren Fruchtnoten und Sie sp\u00fcren die Bergamotte, den knackigen Apfel und den warmen Zimt in der Luft um Sie herum. W\u00e4hrend dieser entz\u00fcckende Beginn Ihr Herz zu einem Gef\u00fchl purer Zufriedenheit erhebt, verschmilzt der k\u00f6stliche Duft sanft und nahtlos mit den warmen und w\u00fcrzigen Noten von Kardamom, goldenem Adlerholz und kostbarem Safran. Der Duft geht sanft in scharfes Zedernholz, gem\u00fctliche Amber und sanften Moschus \u00fcber und hinterl\u00e4sst bei jedem, der ihn tr\u00e4gt, einen stilvollen Eindruck. Kashkha ist ein Unisex-Duft, der f\u00fcr k\u00fchlere Jahreszeiten geeignet ist. Der Duft von Stil.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marke: Swiss Arabian Geeignet f\u00fcr: Damen Menge: 50ml Type: Eau de Parfum Duftfamilie: Orientalisch, Fruchtig, Amber, Holzig Kopfnote: Bergamotte, Apfel, Zimt Herznote: Safran, Kardamom, Oud Basisnote: Zedernholz, Amber, Moschus Herkunftsort: in den Vereinigten Arabischen Emiraten KASHKA EAU DE PARFUM 50ML Kashkha ist ein fruchtiger, w\u00fcrziger Oud-Duft, inspiriert von modernen M\u00e4nnern und Frauen, die in allem, [&#8230;]\n","protected":false},"featured_media":344017,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[87,1080,907,98,1090],"product_tag":[],"class_list":["post-344009","product","type-product","status-publish","has-post-thumbnail","product_cat-sale","product_cat-damenduefte","product_cat-eau-de-parfum","product_cat-parfuem","product_cat-swiss-arabian","product_shipping_class-s-paket-495","first","instock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/product\/344009","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/media\/344017"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/media?parent=344009"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/product_brand?post=344009"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/product_cat?post=344009"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/cs\/wp-json\/wp\/v2\/product_tag?post=344009"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}