{"id":333944,"date":"2022-09-01T13:34:10","date_gmt":"2022-09-01T13:34:10","guid":{"rendered":"https:\/\/ramadan24.de\/?post_type=product&#038;p=333944"},"modified":"2024-11-24T17:58:45","modified_gmt":"2024-11-24T17:58:45","slug":"musk-amber-eau-de-parfum-100ml-hemani-unisex","status":"publish","type":"product","link":"https:\/\/ramadan24.de\/ar\/produkt\/musk-amber-eau-de-parfum-100ml-hemani-unisex\/","title":{"rendered":"Musk Amber Eau de Parfum 100ml Hemani &#8211; Unisex"},"content":{"rendered":"<h1><strong>Musk Amber Eau de Parfum 100ml von Hemani<\/strong><\/h1>\n<ul>\n<li><strong>Marke: <\/strong>Hemani<\/li>\n<li><strong>Volume: <\/strong>100ml<\/li>\n<li><strong>Geschlecht: <\/strong>f\u00fcr Herren und Damen<\/li>\n<li><strong>Kopfnoten: <\/strong>Warm<\/li>\n<li><strong>Konsistenz: <\/strong>Fl\u00fcssig<\/li>\n<li><strong>Herstellungsland: <\/strong>Pakistan<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p data-line-height=\"s\"><strong>Empfohlene Anwendung:<\/strong><\/p>\n<p data-line-height=\"s\">Den Duft auf die Haut auftragen und sanft auf der Innenseite des Handgelenks, Hals und Dekollet\u00e9 verteilen.<\/p>\n<p data-line-height=\"s\">Auf die gesunde Haut auftragen. Entflammbar, Kontakt mit Augen vermeiden. Nicht in die offene Flamme spr\u00fchen.<\/p>\n<div><\/div>\n<div>Versch\u00f6nern und parf\u00fcmieren Sie mit himmlischen D\u00fcften. Musk Amber ist ein heller, kr\u00e4ftiger Duft f\u00fcr M\u00e4nner und Frauen.<\/div>\n<div><\/div>\n<div>Der Duft ist stark, frisch und w\u00fcrzig vom Bernstein, der den ganzen Tag anh\u00e4lt und den Duft Arabiens einl\u00e4dt, der eine moschusartige Spur hinterl\u00e4sst.<\/div>\n<div><\/div>\n<div>Moschusd\u00fcfte sind ein beliebter Duft im K\u00f6nigreich Saudi-Arabien.<\/div>\n<div><\/div>\n<div>HINWEIS: Dieses Parf\u00fcm kann Flecken auf heller Kleidung hinterlassen.<\/div>\n<p><small>Inhaltsstoff: Alkohol Denat, Parfum (Duft), Wasser (Aqua), Linalool, Limonene, Geraniol, Citronellol, Benzyl Alcohol, Amyl Cinnamal. Bitte beachten Sie, dass die Zutatenlisten f\u00fcr Produkte regelm\u00e4\u00dfig aktualisiert werden. Konsultieren Sie die Zutatenliste auf der Produktverpackung f\u00fcr die aktuellste Liste der Inhaltsstoffe.\u00a0<\/small><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Musk Amber Eau de Parfum 100ml von Hemani Marke: Hemani Volume: 100ml Geschlecht: f\u00fcr Herren und Damen Kopfnoten: Warm Konsistenz: Fl\u00fcssig Herstellungsland: Pakistan &nbsp; Empfohlene Anwendung: Den Duft auf die Haut auftragen und sanft auf der Innenseite des Handgelenks, Hals und Dekollet\u00e9 verteilen. Auf die gesunde Haut auftragen. Entflammbar, Kontakt mit Augen vermeiden. Nicht in [&#8230;]\n","protected":false},"featured_media":333945,"template":"","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"product_brand":[],"product_cat":[907,1094,98,1082,1081],"product_tag":[],"class_list":["post-333944","product","type-product","status-publish","has-post-thumbnail","product_cat-eau-de-parfum","product_cat-hemani","product_cat-parfuem","product_cat-parfum-marken","product_cat-unisex-duefte","product_shipping_class-s-paket-495","first","outofstock","sale","taxable","shipping-taxable","purchasable","product-type-simple"],"_links":{"self":[{"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/product\/333944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/media\/333945"}],"wp:attachment":[{"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/media?parent=333944"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/product_brand?post=333944"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/product_cat?post=333944"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/ramadan24.de\/ar\/wp-json\/wp\/v2\/product_tag?post=333944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}